{"id":30,"date":"2023-01-09T13:49:07","date_gmt":"2023-01-09T12:49:07","guid":{"rendered":"https:\/\/ryme.difadi.net\/?page_id=30"},"modified":"2026-01-13T14:05:00","modified_gmt":"2026-01-13T13:05:00","slug":"les-associations","status":"publish","type":"page","link":"https:\/\/ryme-worldwide.co.uk\/fr\/les-associations\/","title":{"rendered":"Partenariats"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"30\" class=\"elementor elementor-30\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-90e5ad4 e-flex e-con-boxed e-con e-parent\" data-id=\"90e5ad4\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bf1fc11 elementor-widget elementor-widget-shortcode\" data-id=\"bf1fc11\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><nav aria-label=\"chapelure\" class=\"rank-math-breadcrumb\"><p><span class=\"last\">Accueil<\/span><\/p><\/nav><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fc5442 elementor-widget elementor-widget-heading\" data-id=\"3fc5442\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Partenariats<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6a926e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f6a926e\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b7c7e05 e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"b7c7e05\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6119894 elementor-widget elementor-widget-text-editor\" data-id=\"6119894\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\" translation-block\">L'un des objectifs de Worldwide Group est \"d'adopter une attitude empathique et proactive \u00e0 l'\u00e9gard de l'environnement dans lequel nous op\u00e9rons<\/b>\". C'est pourquoi, chaque ann\u00e9e, nous essayons d'augmenter notre r\u00e9seau de partenaires et d'associations afin de fournir une solution de meilleure qualit\u00e9, adapt\u00e9e aux diff\u00e9rents contextes.<\/p><p class=\" translation-block\">Gr\u00e2ce \u00e0 ces partenariats, nos entreprises ont pu \u00e9tendre leur port\u00e9e et am\u00e9liorer leurs offres de services, tout en contribuant \u00e0 la promotion de pratiques durables et responsables dans diff\u00e9rents secteurs. Ryme Worldwide est fi\u00e8re de travailler avec ses partenaires pour avoir un impact positif sur le monde et continuer \u00e0 <b> travailler pour un avenir plus durable et plus s\u00fbr.<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-34bd3c2 e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"34bd3c2\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;tilt&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 1000 100\" preserveaspectratio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eb29c76 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"eb29c76\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:300}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0c60d99 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"0c60d99\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Partenariats Europe<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfe9cef elementor-arrows-position-outside elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-loop-carousel\" data-id=\"bfe9cef\" data-element_type=\"widget\" data-settings=\"{&quot;template_id&quot;:&quot;4896&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;slides_to_show_tablet&quot;:&quot;3&quot;,&quot;_skin&quot;:&quot;post&quot;,&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;.elementor-loop-container&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_sides&quot;:&quot;none&quot;,&quot;arrows&quot;:&quot;yes&quot;,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-carousel.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"swiper elementor-loop-container elementor-grid\" role=\"list\" dir=\"ltr\">\n\t\t\t\t<div class=\"swiper-wrapper\" aria-live=\"polite\">\n\t\t<style id=\"loop-4896\">.elementor-4896 .elementor-element.elementor-element-79a5ab5{--display:flex;--flex-direction:column;--container-widget-width:100%;--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:space-between;border-style:solid;--border-style:solid;border-width:1px 1px 1px 1px;--border-top-width:1px;--border-right-width:1px;--border-bottom-width:1px;--border-left-width:1px;border-color:var( --e-global-color-secondary );--border-color:var( --e-global-color-secondary );--padding-top:0px;--padding-bottom:0px;--padding-left:0px;--padding-right:0px;}.elementor-4896 .elementor-element.elementor-element-79a5ab5:not(.elementor-motion-effects-element-type-background), .elementor-4896 .elementor-element.elementor-element-79a5ab5 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:var( --e-global-color-f28e0c1 );}.elementor-4896 .elementor-element.elementor-element-8d52480 > .elementor-widget-container{padding:10px 10px 10px 10px;}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"4896\" class=\"elementor elementor-4896 swiper-slide e-loop-item e-loop-item-4748 post-4748 asociaciones type-asociaciones status-publish has-post-thumbnail hentry ubicacion-europa\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-79a5ab5 bucle-asociaciones e-flex e-con-boxed e-con e-parent\" data-id=\"79a5ab5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"http:\/\/www.aepvburgos.com\/aepv\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d52480 elementor-widget elementor-widget-shortcode\" data-id=\"8d52480\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><img decoding=\"async\" src=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2023\/04\/3-Logo_AEPV.png\" title=\"Association des entreprises du parc industriel de Villalonqu\u00e9jar\" alt=\"Association des entreprises du parc industriel de Villalonqu\u00e9jar\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"4896\" class=\"elementor elementor-4896 swiper-slide e-loop-item e-loop-item-11603 post-11603 asociaciones type-asociaciones status-publish has-post-thumbnail hentry ubicacion-europa\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-79a5ab5 bucle-asociaciones e-flex e-con-boxed e-con e-parent\" data-id=\"79a5ab5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/asa-verband.de\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d52480 elementor-widget elementor-widget-shortcode\" data-id=\"8d52480\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><img decoding=\"async\" src=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2023\/07\/6-ASA_Verband.png\" title=\"ASA-Verband-Associations-Ryme-Worldwide\" alt=\"ASA-Vervand-Associations-Ryme-Dans le Monde\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"4896\" class=\"elementor elementor-4896 swiper-slide e-loop-item e-loop-item-12159 post-12159 asociaciones type-asociaciones status-publish has-post-thumbnail hentry ubicacion-europa\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-79a5ab5 bucle-asociaciones e-flex e-con-boxed e-con e-parent\" data-id=\"79a5ab5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/gea.co.uk\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d52480 elementor-widget elementor-widget-shortcode\" data-id=\"8d52480\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><img decoding=\"async\" src=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2024\/02\/GEA-Logo-PNG.png\" title=\"GEA_Garage_Equipment_Association_Ryme_Worldwide_Partnership\" alt=\"GEA_Garage_Equipment_Association_Ryme_Worldwide_Partnership\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"4896\" class=\"elementor elementor-4896 swiper-slide e-loop-item e-loop-item-11614 post-11614 asociaciones type-asociaciones status-publish has-post-thumbnail hentry ubicacion-asa ubicacion-europa\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-79a5ab5 bucle-asociaciones e-flex e-con-boxed e-con e-parent\" data-id=\"79a5ab5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/workshop-net.net\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d52480 elementor-widget elementor-widget-shortcode\" data-id=\"8d52480\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><img decoding=\"async\" src=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2023\/07\/7-ASA_Network-e1688380556509.png\" title=\"ASA-Network-Ryme-Worldwide-GmbH\" alt=\"ASA-Network-Ryme-Worldwide-GmbH\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"4896\" class=\"elementor elementor-4896 swiper-slide e-loop-item e-loop-item-4749 post-4749 asociaciones type-asociaciones status-publish has-post-thumbnail hentry ubicacion-europa\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-79a5ab5 bucle-asociaciones e-flex e-con-boxed e-con e-parent\" data-id=\"79a5ab5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"http:\/\/afiba.org\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d52480 elementor-widget elementor-widget-shortcode\" data-id=\"8d52480\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><img decoding=\"async\" src=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2023\/04\/4-AFIBA.png\" title=\"Association des fabricants, distributeurs et importateurs de biens d&#039;\u00e9quipement\" alt=\"Association des fabricants, distributeurs et importateurs de biens d&#039;\u00e9quipement\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"4896\" class=\"elementor elementor-4896 swiper-slide e-loop-item e-loop-item-4747 post-4747 asociaciones type-asociaciones status-publish has-post-thumbnail hentry ubicacion-europa\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-79a5ab5 bucle-asociaciones e-flex e-con-boxed e-con e-parent\" data-id=\"79a5ab5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/www.aeca-itv.com\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d52480 elementor-widget elementor-widget-shortcode\" data-id=\"8d52480\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><img decoding=\"async\" src=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2023\/04\/2-AECA.png\" title=\"Association espagnole des entit\u00e9s collaborant avec l&#039;administration pour l&#039;inspection technique des v\u00e9hicules (Asociaci\u00f3n Espa\u00f1ola de Entidades Colaboradoras de la Administraci\u00f3n en la Inspecci\u00f3n T\u00e9cnica de Veh\u00edculos)\" alt=\"Association espagnole des entit\u00e9s collaborant avec l&#039;administration pour l&#039;inspection technique des v\u00e9hicules (Asociaci\u00f3n Espa\u00f1ola de Entidades Colaboradoras de la Administraci\u00f3n en la Inspecci\u00f3n T\u00e9cnica de Veh\u00edculos)\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"4896\" class=\"elementor elementor-4896 swiper-slide e-loop-item e-loop-item-4750 post-4750 asociaciones type-asociaciones status-publish has-post-thumbnail hentry ubicacion-europa\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-79a5ab5 bucle-asociaciones e-flex e-con-boxed e-con e-parent\" data-id=\"79a5ab5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/www.faeburgos.org\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d52480 elementor-widget elementor-widget-shortcode\" data-id=\"8d52480\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><img decoding=\"async\" src=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2023\/04\/5-FAE_Burgos.png\" title=\"Conf\u00e9d\u00e9ration des associations d&#039;entreprises de Burgos\" alt=\"Conf\u00e9d\u00e9ration des associations d&#039;entreprises de Burgos\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"4896\" class=\"elementor elementor-4896 swiper-slide e-loop-item e-loop-item-4746 post-4746 asociaciones type-asociaciones status-publish has-post-thumbnail hentry ubicacion-europa\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-79a5ab5 bucle-asociaciones e-flex e-con-boxed e-con e-parent\" data-id=\"79a5ab5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/citainsp.org\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d52480 elementor-widget elementor-widget-shortcode\" data-id=\"8d52480\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><img decoding=\"async\" src=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2023\/04\/1-CITA_Europa.png\" title=\"Association mondiale des autorit\u00e9s habilit\u00e9es \u00e0 faire appliquer la r\u00e9glementation sur les v\u00e9hicules et des soci\u00e9t\u00e9s habilit\u00e9es actives dans le domaine de l&#039;application de la r\u00e9glementation sur les v\u00e9hicules\" alt=\"Association mondiale des autorit\u00e9s habilit\u00e9es \u00e0 faire appliquer la r\u00e9glementation sur les v\u00e9hicules et des soci\u00e9t\u00e9s habilit\u00e9es actives dans le domaine de l&#039;application de la r\u00e9glementation sur les v\u00e9hicules\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Pr\u00e9c\u00e9dent\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t<\/div>\n\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Suivant\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fd86fec e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"fd86fec\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:300}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bf77ba4 elementor-widget elementor-widget-heading\" data-id=\"bf77ba4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Trusted partners<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1da31a elementor-widget elementor-widget-gallery\" data-id=\"c1da31a\" data-element_type=\"widget\" id=\"partnership\" data-settings=\"{&quot;columns&quot;:6,&quot;lazyload&quot;:&quot;yes&quot;,&quot;gallery_layout&quot;:&quot;grid&quot;,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;aspect_ratio&quot;:&quot;3:2&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2025\/12\/AC-Hydraulics.png\" data-width=\"295\" data-height=\"101\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2025\/12\/Bullworthy-Garage-Equipment.png\" data-width=\"334\" data-height=\"151\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2025\/12\/Cormach-SRL.png\" data-width=\"274\" data-height=\"76\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2025\/12\/Crypton.png\" data-width=\"323\" data-height=\"38\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2025\/12\/DEA-Worklab.png\" data-width=\"128\" data-height=\"122\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2025\/12\/GEA-Logo-PNG-2048x1533.png\" data-width=\"2048\" data-height=\"1533\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2025\/12\/Gott-Logo.jpg\" data-width=\"158\" data-height=\"82\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2025\/12\/MAN.png\" data-width=\"198\" data-height=\"198\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2025\/12\/McLaren.jpg\" data-width=\"223\" data-height=\"182\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2025\/12\/Ministry-Of-Defense.png\" data-width=\"120\" data-height=\"97\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2025\/12\/Premier-Pits.jpg\" data-width=\"272\" data-height=\"98\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2025\/12\/Samoa.png\" data-width=\"240\" data-height=\"40\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be4a4a7 elementor-arrows-position-outside elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-loop-carousel\" data-id=\"be4a4a7\" data-element_type=\"widget\" data-settings=\"{&quot;template_id&quot;:&quot;4896&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;slides_to_show_tablet&quot;:&quot;3&quot;,&quot;_skin&quot;:&quot;post&quot;,&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;.elementor-loop-container&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_sides&quot;:&quot;none&quot;,&quot;arrows&quot;:&quot;yes&quot;,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-carousel.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"swiper elementor-loop-container elementor-grid\" role=\"list\" dir=\"ltr\">\n\t\t\t\t<div class=\"swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"4896\" class=\"elementor elementor-4896 swiper-slide e-loop-item e-loop-item-4753 post-4753 asociaciones type-asociaciones status-publish has-post-thumbnail hentry ubicacion-resto-del-mundo\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-79a5ab5 bucle-asociaciones e-flex e-con-boxed e-con e-parent\" data-id=\"79a5ab5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/www.aamva.org\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d52480 elementor-widget elementor-widget-shortcode\" data-id=\"8d52480\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><img decoding=\"async\" src=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2023\/04\/3-AAMVA.jpeg\" title=\"Association am\u00e9ricaine des administrateurs de v\u00e9hicules \u00e0 moteur\" alt=\"Association am\u00e9ricaine des administrateurs de v\u00e9hicules \u00e0 moteur\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"4896\" class=\"elementor elementor-4896 swiper-slide e-loop-item e-loop-item-4758 post-4758 asociaciones type-asociaciones status-publish has-post-thumbnail hentry ubicacion-resto-del-mundo\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-79a5ab5 bucle-asociaciones e-flex e-con-boxed e-con e-parent\" data-id=\"79a5ab5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/programacalac.com\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d52480 elementor-widget elementor-widget-shortcode\" data-id=\"8d52480\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><img decoding=\"async\" src=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2023\/04\/8-Calac.jpg\" title=\"Programme sur le climat et l&#039;air pur dans les villes d&#039;Am\u00e9rique latine - Plus\" alt=\"Programme sur le climat et l&#039;air pur dans les villes d&#039;Am\u00e9rique latine - Plus\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"4896\" class=\"elementor elementor-4896 swiper-slide e-loop-item e-loop-item-4757 post-4757 asociaciones type-asociaciones status-publish has-post-thumbnail hentry ubicacion-resto-del-mundo\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-79a5ab5 bucle-asociaciones e-flex e-con-boxed e-con e-parent\" data-id=\"79a5ab5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/www.canieti.org\/Inicio.aspx\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d52480 elementor-widget elementor-widget-shortcode\" data-id=\"8d52480\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><img decoding=\"async\" src=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2023\/04\/7-Canieti.png\" title=\"Chambre nationale de l&#039;industrie \u00e9lectronique des t\u00e9l\u00e9communications et des technologies (C\u00e1mara Nacional de la Industria Electr\u00f3nica de Telecomunicaciones y Tecnolog\u00edas)\" alt=\"Chambre nationale de l&#039;industrie \u00e9lectronique des t\u00e9l\u00e9communications et des technologies (C\u00e1mara Nacional de la Industria Electr\u00f3nica de Telecomunicaciones y Tecnolog\u00edas)\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"4896\" class=\"elementor elementor-4896 swiper-slide e-loop-item e-loop-item-6170 post-6170 asociaciones type-asociaciones status-publish has-post-thumbnail hentry ubicacion-resto-del-mundo\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-79a5ab5 bucle-asociaciones e-flex e-con-boxed e-con e-parent\" data-id=\"79a5ab5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/www.cawa.org\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d52480 elementor-widget elementor-widget-shortcode\" data-id=\"8d52480\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><img decoding=\"async\" src=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2023\/04\/9-CAWA.png\" title=\"CAWA association commerciale \u00e0 but non lucratif repr\u00e9sentant les fabricants de pi\u00e8ces automobiles, les grossistes, les distributeurs d&#039;entrep\u00f4ts, les d\u00e9taillants et les groupes de programmes.\" alt=\"CAWA association commerciale \u00e0 but non lucratif repr\u00e9sentant les fabricants de pi\u00e8ces automobiles, les grossistes, les distributeurs d&#039;entrep\u00f4ts, les d\u00e9taillants et les groupes de programmes.\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"4896\" class=\"elementor elementor-4896 swiper-slide e-loop-item e-loop-item-4751 post-4751 asociaciones type-asociaciones status-publish has-post-thumbnail hentry ubicacion-resto-del-mundo\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-79a5ab5 bucle-asociaciones e-flex e-con-boxed e-con e-parent\" data-id=\"79a5ab5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/citainsp.org\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d52480 elementor-widget elementor-widget-shortcode\" data-id=\"8d52480\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><img decoding=\"async\" src=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2023\/04\/1-CITA_Europa.png\" title=\"Association mondiale des autorit\u00e9s habilit\u00e9es \u00e0 faire appliquer la r\u00e9glementation sur les v\u00e9hicules et des soci\u00e9t\u00e9s habilit\u00e9es actives dans le domaine de l&#039;application de la r\u00e9glementation sur les v\u00e9hicules\" alt=\"Association mondiale des autorit\u00e9s habilit\u00e9es \u00e0 faire appliquer la r\u00e9glementation sur les v\u00e9hicules et des soci\u00e9t\u00e9s habilit\u00e9es actives dans le domaine de l&#039;application de la r\u00e9glementation sur les v\u00e9hicules\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"4896\" class=\"elementor elementor-4896 swiper-slide e-loop-item e-loop-item-12248 post-12248 asociaciones type-asociaciones status-publish has-post-thumbnail hentry ubicacion-resto-del-mundo\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-79a5ab5 bucle-asociaciones e-flex e-con-boxed e-con e-parent\" data-id=\"79a5ab5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/www.clautjalisco.org.mx\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d52480 elementor-widget elementor-widget-shortcode\" data-id=\"8d52480\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><img decoding=\"async\" src=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2024\/04\/10-Cluster_Automotriz_de_Jalisco.png\" title=\"Cluster-partenaire-environnemental-mondial-automobile-Jalisco\" alt=\"Cluster-partenaire-environnemental-mondial-automobile-Jalisco\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"4896\" class=\"elementor elementor-4896 swiper-slide e-loop-item e-loop-item-4755 post-4755 asociaciones type-asociaciones status-publish has-post-thumbnail hentry ubicacion-resto-del-mundo\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-79a5ab5 bucle-asociaciones e-flex e-con-boxed e-con e-parent\" data-id=\"79a5ab5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/www.ccair.org\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d52480 elementor-widget elementor-widget-shortcode\" data-id=\"8d52480\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><img decoding=\"async\" src=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2023\/04\/5-Coalition_for_Clean_Air.jpg\" title=\"Association californienne d&#039;organisations et d&#039;entit\u00e9s collaborant \u00e0 la sant\u00e9 publique, \u00e0 l&#039;am\u00e9lioration de la qualit\u00e9 de l&#039;air et \u00e0 la pr\u00e9vention du changement climatique depuis 1971.\" alt=\"Association californienne d&#039;organisations et d&#039;entit\u00e9s collaborant \u00e0 la sant\u00e9 publique, \u00e0 l&#039;am\u00e9lioration de la qualit\u00e9 de l&#039;air et \u00e0 la pr\u00e9vention du changement climatique depuis 1971.\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"4896\" class=\"elementor elementor-4896 swiper-slide e-loop-item e-loop-item-4752 post-4752 asociaciones type-asociaciones status-publish has-post-thumbnail hentry ubicacion-resto-del-mundo\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-79a5ab5 bucle-asociaciones e-flex e-con-boxed e-con e-parent\" data-id=\"79a5ab5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/www.ghsa.org\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d52480 elementor-widget elementor-widget-shortcode\" data-id=\"8d52480\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><img decoding=\"async\" src=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2023\/04\/2-GHSA.jpg\" title=\"Association des gouverneurs pour la s\u00e9curit\u00e9 routi\u00e8re des \u00c9tats-Unis\" alt=\"Association des gouverneurs pour la s\u00e9curit\u00e9 routi\u00e8re des \u00c9tats-Unis\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"4896\" class=\"elementor elementor-4896 swiper-slide e-loop-item e-loop-item-4754 post-4754 asociaciones type-asociaciones status-publish has-post-thumbnail hentry ubicacion-resto-del-mundo\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-79a5ab5 bucle-asociaciones e-flex e-con-boxed e-con e-parent\" data-id=\"79a5ab5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/www.obdclearinghouse.com\/IMSolutions\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d52480 elementor-widget elementor-widget-shortcode\" data-id=\"8d52480\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><img decoding=\"async\" src=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2023\/04\/4-I-M_Solutions.png\" title=\"Association nord-am\u00e9ricaine des fournisseurs de programmes d&#039;inspection et de maintenance\" alt=\"Association nord-am\u00e9ricaine des fournisseurs de programmes d&#039;inspection et de maintenance\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"4896\" class=\"elementor elementor-4896 swiper-slide e-loop-item e-loop-item-4756 post-4756 asociaciones type-asociaciones status-publish has-post-thumbnail hentry ubicacion-resto-del-mundo\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-79a5ab5 bucle-asociaciones e-flex e-con-boxed e-con e-parent\" data-id=\"79a5ab5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/www.texasvehicleinspections.com\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d52480 elementor-widget elementor-widget-shortcode\" data-id=\"8d52480\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><img decoding=\"async\" src=\"https:\/\/ryme-worldwide.co.uk\/wp-content\/uploads\/2023\/04\/6-TSIA.png\" title=\"Association pour l&#039;inspection des v\u00e9hicules dans l&#039;\u00c9tat du Texas, \u00c9tats-Unis\" alt=\"Association pour l&#039;inspection des v\u00e9hicules dans l&#039;\u00c9tat du Texas, \u00c9tats-Unis\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Pr\u00e9c\u00e9dent\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t<\/div>\n\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Suivant\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>L&#039;un des objectifs que nous nous sommes fix\u00e9s chez Worldwide Group est \u00ab\u00a0Adopter un comportement empathique et proactif avec l&#039;environnement dans lequel nous exer\u00e7ons notre activit\u00e9\u00a0\u00bb c&#039;est pourquoi, chaque ann\u00e9e, nous essayons d&#039;augmenter notre r\u00e9seau de collaborateurs et d&#039;associations pour apporter une meilleure solution de qualit\u00e9. et adapt\u00e9s \u00e0 diff\u00e9rents contextes. \u00c0 travers de [\u2026]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-30","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/ryme-worldwide.co.uk\/fr\/wp-json\/wp\/v2\/pages\/30","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ryme-worldwide.co.uk\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ryme-worldwide.co.uk\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ryme-worldwide.co.uk\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ryme-worldwide.co.uk\/fr\/wp-json\/wp\/v2\/comments?post=30"}],"version-history":[{"count":92,"href":"https:\/\/ryme-worldwide.co.uk\/fr\/wp-json\/wp\/v2\/pages\/30\/revisions"}],"predecessor-version":[{"id":16678,"href":"https:\/\/ryme-worldwide.co.uk\/fr\/wp-json\/wp\/v2\/pages\/30\/revisions\/16678"}],"wp:attachment":[{"href":"https:\/\/ryme-worldwide.co.uk\/fr\/wp-json\/wp\/v2\/media?parent=30"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}